{"id":178,"date":"2013-12-03T20:44:36","date_gmt":"2013-12-03T23:44:36","guid":{"rendered":"http:\/\/songkol.com\/WordPress3\/?p=178"},"modified":"2013-12-12T20:50:00","modified_gmt":"2013-12-12T23:50:00","slug":"montevideo-nous-voila","status":"publish","type":"post","link":"http:\/\/songkol.com\/WordPress3\/blog\/2013\/12\/03\/montevideo-nous-voila\/","title":{"rendered":"Montevideo, nous voil\u00e0!"},"content":{"rendered":"<p>Nous voil\u00e0 depuis hier soir \u00e0 Montevideo, Uruguay. Nous y sommes arriv\u00e9s par bateau avec le Buquebus qui relie plusieurs fois par jour Buenos Aires \u00e0 Montevideo. C&rsquo;est un bel orage qui nous accueille \u00e0 notre arriv\u00e9e: pluie diluvienne, vent de folie. Lionel a tent\u00e9 de nous convaincre d&rsquo;aller \u00e0 l&rsquo;h\u00f4tel \u00e0 pied mais finalement on a pas eu de mal \u00e0 prendre un taxi! C&rsquo;est avec beaucoup de plaisir que nous avons d\u00e9couvert notre charmant hostel qui allait nous h\u00e9berger ces prochains jours. La Posada el sur, situ\u00e9e \u00e0 quelques rues du port, est charmante, am\u00e9nag\u00e9e avec go\u00fbt. Nous contactons d\u00e8s le matin notre transitaire ici en Uruguay qui va nous aider \u00e0 r\u00e9cup\u00e9rer le camping-car. Il est fran\u00e7ais, ce qui facilite grandement les \u00e9changes. Olivier Chetanneau nous indique dores et d\u00e9j\u00e0 que le cargo a du retard et qu&rsquo;il n&rsquo;est pas attendu avant la fin de la semaine&#8230; Tant pis, nous allons d\u00e9couvrir la ville en attendant.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous voil\u00e0 depuis hier soir \u00e0 Montevideo, Uruguay. Nous y sommes arriv\u00e9s par bateau avec le Buquebus qui relie plusieurs fois par jour Buenos Aires \u00e0 Montevideo. C&rsquo;est un bel orage qui nous accueille \u00e0 notre arriv\u00e9e: pluie diluvienne, vent de folie. Lionel a tent\u00e9 de nous convaincre d&rsquo;aller \u00e0 l&rsquo;h\u00f4tel \u00e0 pied mais finalement [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[9],"tags":[],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4uy6M-2S","jetpack_likes_enabled":true,"_links":{"self":[{"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/posts\/178"}],"collection":[{"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/comments?post=178"}],"version-history":[{"count":6,"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/posts\/178\/revisions"}],"predecessor-version":[{"id":236,"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/posts\/178\/revisions\/236"}],"wp:attachment":[{"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/media?parent=178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/categories?post=178"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/tags?post=178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}