{"id":139,"date":"2013-12-01T20:35:41","date_gmt":"2013-12-01T23:35:41","guid":{"rendered":"http:\/\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg"},"modified":"2016-02-15T09:39:42","modified_gmt":"2016-02-15T08:39:42","slug":"dsc00210","status":"inherit","type":"attachment","link":"http:\/\/songkol.com\/WordPress3\/dsc00210\/","title":{"rendered":"FERIA DE MATATEDROS \/ Foire tr\u00e8s anim\u00e9e se d\u00e9roule chaque week-end \u00e0 Mataderos. Ici la carrera de sortija au cours de laquelle des cavaliers en tenue de gardien de troupeau de la pampa se lancent au galop pour attraper un petit anneau suspendu \u00e0 un ruban."},"author":3,"comment_status":"closed","ping_status":"open","template":"","meta":{"spay_email":""},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a4uy6M-2f","jetpack_likes_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/i0.wp.com\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg'><img width=\"300\" height=\"168\" src=\"https:\/\/i0.wp.com\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg?fit=300%2C168\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg?w=1920 1920w, https:\/\/i0.wp.com\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg?resize=300%2C168 300w, https:\/\/i0.wp.com\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg?resize=1024%2C576 1024w, https:\/\/i0.wp.com\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg?w=1536 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-attachment-id=\"139\" data-permalink=\"http:\/\/songkol.com\/WordPress3\/dsc00210\/\" data-orig-file=\"https:\/\/i0.wp.com\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg?fit=1920%2C1080\" data-orig-size=\"1920,1080\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DSC-HX50V&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1385914934&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.51&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.0015625&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"FERIA DE MATATEDROS \/ Foire tr\u00e8s anim\u00e9e se d\u00e9roule chaque week-end \u00e0 Mataderos. Ici la carrera de sortija au cours de laquelle des cavaliers en tenue de gardien de troupeau de la pampa se lancent au galop pour attraper un petit anneau suspendu \u00e0 un ruban.\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;FERIA DE MATATEDROS \/ Foire tr\u00e8s anim\u00e9e se d\u00e9roule chaque week-end \u00e0 Mataderos. Ici la carrera de sortija au cours de laquelle des cavaliers en tenue de gardien de troupeau de la pampa se lancent au galop pour attraper un petit anneau suspendu \u00e0 un ruban.&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg?fit=300%2C168\" data-large-file=\"https:\/\/i0.wp.com\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg?fit=768%2C432\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>FERIA DE MATATEDROS \/ Foire tr\u00e8s anim\u00e9e se d\u00e9roule chaque week-end \u00e0 Mataderos. Ici la carrera de sortija au cours de laquelle des cavaliers en tenue de gardien de troupeau de la pampa se lancent au galop pour attraper un petit anneau suspendu \u00e0 un ruban.<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1080,"file":"2013\/12\/DSC00210.jpg","sizes":{"thumbnail":{"file":"DSC00210-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg?resize=150%2C150"},"medium":{"file":"DSC00210-300x168.jpg","width":300,"height":168,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg?fit=300%2C168"},"large":{"file":"DSC00210-1024x576.jpg","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg?fit=768%2C432"},"full":{"file":"DSC00210.jpg?fit=1920%2C1080","width":1920,"height":1080,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg?fit=1920%2C1080"}},"image_meta":{"aperture":4,"credit":"","camera":"DSC-HX50V","caption":"","created_timestamp":1385914934,"copyright":"","focal_length":"5.51","iso":"80","shutter_speed":"0.0015625","title":""}},"post":null,"source_url":"http:\/\/songkol.com\/WordPress3\/wp-content\/uploads\/2013\/12\/DSC00210.jpg","_links":{"self":[{"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/media\/139"}],"collection":[{"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/songkol.com\/WordPress3\/wp-json\/wp\/v2\/comments?post=139"}]}}